{"id":26906,"date":"2021-10-20T11:13:57","date_gmt":"2021-10-20T02:13:57","guid":{"rendered":"https:\/\/qrec.kyushu-u.ac.jp\/?p=26906\/"},"modified":"2021-10-20T11:13:57","modified_gmt":"2021-10-20T02:13:57","slug":"20211019e_2","status":"publish","type":"news","link":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/20211019e_2\/","title":{"rendered":"[Change of lecture schedule] Advanced Lecture in Technology Based Entrepreneurship [For graduate students]"},"content":{"rendered":"<p><center><font size=\"+3\" color=\"#008000\">Fall quarter Fridays Lecture 6&#038;7<br \/>\nAdvanced Lecture in Technology Based Entrepreneurship<br \/>\n<\/font><\/p>\n<p>There has been a change in the lecture schedule of the current Advanced Lecture in Technology Based Entrepreneurship course.<\/p>\n<p>\u3010Before the change\u3011<br \/>\n10\/8, 15, 22, 29, 11\/12, 19, 26, 12\/3<br \/>\n<font color=\"ff0000\"><strong><u>\u3010After the change\u3011<\/u><\/strong><\/font><br \/>\n10\/8, 15, 22, 29,<font color=\"ff0000\"><strong><u>11\/5<\/u><\/strong><\/font>, 12, 19, 26,<del><strong>12\/3<\/strong><\/del><\/p>\n<p>*Please note that 11\/26 will be the last day of class.<br \/>\n<\/center><\/p>\n","protected":false},"featured_media":26908,"menu_order":0,"template":"","newstag":[],"class_list":["post-26906","news","type-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Fall quarter Fridays Lecture 6&amp;7 Advanced Lecture in Technology Based Entrepreneurship There has been a change in the lecture schedule of the current Advanced Lecture in Technology Based Entrepreneurship course. \u3010Before the change\u3011 10\/8, 15, 22, 29, 11\/12, 19, 26, 12\/3 \u3010After the change\u3011 10\/8, 15, 22, 29,11\/5, 12, 19, 26,12\/3 *Please note that 11\/26\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/20211019e_2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"QREC \u4e5d\u5dde\u5927\u5b66\u30ed\u30d0\u30fc\u30c8\uff65\u30d5\u30a1\u30f3 \/\u30a2\u30f3\u30c8\u30ec\u30d7\u30ec\u30ca\u30fc\u30b7\u30c3\u30d7\uff65\u30bb\u30f3\u30bf\u30fc\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"[Change of lecture schedule] Advanced Lecture in Technology Based Entrepreneurship [For graduate students] - QREC \u4e5d\u5dde\u5927\u5b66\u30ed\u30d0\u30fc\u30c8\uff65\u30d5\u30a1\u30f3 \/\u30a2\u30f3\u30c8\u30ec\u30d7\u30ec\u30ca\u30fc\u30b7\u30c3\u30d7\uff65\u30bb\u30f3\u30bf\u30fc\" \/>\n\t\t<meta property=\"og:description\" content=\"Fall quarter Fridays Lecture 6&amp;7 Advanced Lecture in Technology Based Entrepreneurship There has been a change in the lecture schedule of the current Advanced Lecture in Technology Based Entrepreneurship course. \u3010Before the change\u3011 10\/8, 15, 22, 29, 11\/12, 19, 26, 12\/3 \u3010After the change\u3011 10\/8, 15, 22, 29,11\/5, 12, 19, 26,12\/3 *Please note that 11\/26\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/20211019e_2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/qrec.kyushu-u.ac.jp\/kanri-new\/wp-content\/uploads\/2023\/09\/ogp.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/qrec.kyushu-u.ac.jp\/kanri-new\/wp-content\/uploads\/2023\/09\/ogp.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-10-20T02:13:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-10-20T02:13:57+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"[Change of lecture schedule] Advanced Lecture in Technology Based Entrepreneurship [For graduate students] - QREC \u4e5d\u5dde\u5927\u5b66\u30ed\u30d0\u30fc\u30c8\uff65\u30d5\u30a1\u30f3 \/\u30a2\u30f3\u30c8\u30ec\u30d7\u30ec\u30ca\u30fc\u30b7\u30c3\u30d7\uff65\u30bb\u30f3\u30bf\u30fc\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Fall quarter Fridays Lecture 6&amp;7 Advanced Lecture in Technology Based Entrepreneurship There has been a change in the lecture schedule of the current Advanced Lecture in Technology Based Entrepreneurship course. \u3010Before the change\u3011 10\/8, 15, 22, 29, 11\/12, 19, 26, 12\/3 \u3010After the change\u3011 10\/8, 15, 22, 29,11\/5, 12, 19, 26,12\/3 *Please note that 11\/26\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/qrec.kyushu-u.ac.jp\/kanri-new\/wp-content\/uploads\/2023\/09\/ogp.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/news\\\/20211019e_2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/#listItem\",\"position\":1,\"name\":\"TOP\",\"item\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/news\\\/#listItem\",\"name\":\"\\u8b1b\\u7fa9\\u30fb\\u30a4\\u30d9\\u30f3\\u30c8\\u60c5\\u5831\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/news\\\/#listItem\",\"position\":2,\"name\":\"\\u8b1b\\u7fa9\\u30fb\\u30a4\\u30d9\\u30f3\\u30c8\\u60c5\\u5831\",\"item\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/news\\\/20211019e_2\\\/#listItem\",\"name\":\"[Change of lecture schedule] Advanced Lecture in Technology Based Entrepreneurship [For graduate students]\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/#listItem\",\"name\":\"TOP\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/news\\\/20211019e_2\\\/#listItem\",\"position\":3,\"name\":\"[Change of lecture schedule] Advanced Lecture in Technology Based Entrepreneurship [For graduate students]\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/news\\\/#listItem\",\"name\":\"\\u8b1b\\u7fa9\\u30fb\\u30a4\\u30d9\\u30f3\\u30c8\\u60c5\\u5831\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/#organization\",\"name\":\"QREC\",\"description\":\"QREC\\u306f\\u30a2\\u30f3\\u30c8\\u30ec\\u30d7\\u30ec\\u30ca\\u30fc\\u30b7\\u30c3\\u30d7\\u306b\\u3064\\u3044\\u3066\\u5b66\\u751f\\u81ea\\u3089\\u304c\\u5b66\\u3076\\u6a5f\\u4f1a\\u3092\\u63d0\\u4f9b\\u3057\\u3066\\u3044\\u307e\\u3059\\u300230\\u4ee5\\u4e0a\\u306e\\u79d1\\u76ee\\u304b\\u3089\\u306a\\u308b\\u6388\\u696d\\u3068\\u3001\\u5b9f\\u8df5\\u306e\\u5834\\u3092\\u63d0\\u4f9b\\u3059\\u308b\\u30c8\\u30e9\\u30a4\\u30a2\\u30eb\\u3067\\u69cb\\u6210\\u3055\\u308c\\u3066\\u3044\\u307e\\u3059\\u3002\\u3053\\u3053\\u306b\\u3042\\u308b\\u6a5f\\u4f1a\\u3092\\u98df\\u3089\\u3044\\u5c3d\\u304f\\u3057\\u3066\\u3001\\u672a\\u6765\\u3092\\u5207\\u308a\\u62d3\\u304f\\u7ce7\\u306b\\u3057\\u3066\\u304f\\u3060\\u3055\\u3044\\u3002\",\"url\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/kanri-new\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/favicon-base.png\",\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/news\\\/20211019e_2\\\/#organizationLogo\",\"width\":260,\"height\":260},\"image\":{\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/news\\\/20211019e_2\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/news\\\/20211019e_2\\\/#webpage\",\"url\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/news\\\/20211019e_2\\\/\",\"name\":\"[Change of lecture schedule] Advanced Lecture in Technology Based Entrepreneurship [For graduate students] - QREC \\u4e5d\\u5dde\\u5927\\u5b66\\u30ed\\u30d0\\u30fc\\u30c8\\uff65\\u30d5\\u30a1\\u30f3 \\\/\\u30a2\\u30f3\\u30c8\\u30ec\\u30d7\\u30ec\\u30ca\\u30fc\\u30b7\\u30c3\\u30d7\\uff65\\u30bb\\u30f3\\u30bf\\u30fc\",\"description\":\"Fall quarter Fridays Lecture 6&7 Advanced Lecture in Technology Based Entrepreneurship There has been a change in the lecture schedule of the current Advanced Lecture in Technology Based Entrepreneurship course. \\u3010Before the change\\u3011 10\\\/8, 15, 22, 29, 11\\\/12, 19, 26, 12\\\/3 \\u3010After the change\\u3011 10\\\/8, 15, 22, 29,11\\\/5, 12, 19, 26,12\\\/3 *Please note that 11\\\/26\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/news\\\/20211019e_2\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/kanri-new\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/806b7c2575c5a21af601c3026ca0d2a0.png\",\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/news\\\/20211019e_2\\\/#mainImage\",\"width\":1920,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/news\\\/20211019e_2\\\/#mainImage\"},\"datePublished\":\"2021-10-20T11:13:57+09:00\",\"dateModified\":\"2021-10-20T11:13:57+09:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/\",\"name\":\"QREC \\u4e5d\\u5dde\\u5927\\u5b66\\u30ed\\u30d0\\u30fc\\u30c8\\uff65\\u30d5\\u30a1\\u30f3 \\\/\\u30a2\\u30f3\\u30c8\\u30ec\\u30d7\\u30ec\\u30ca\\u30fc\\u30b7\\u30c3\\u30d7\\uff65\\u30bb\\u30f3\\u30bf\\u30fc\",\"description\":\"QREC\\u306f\\u30a2\\u30f3\\u30c8\\u30ec\\u30d7\\u30ec\\u30ca\\u30fc\\u30b7\\u30c3\\u30d7\\u306b\\u3064\\u3044\\u3066\\u5b66\\u751f\\u81ea\\u3089\\u304c\\u5b66\\u3076\\u6a5f\\u4f1a\\u3092\\u63d0\\u4f9b\\u3057\\u3066\\u3044\\u307e\\u3059\\u300230\\u4ee5\\u4e0a\\u306e\\u79d1\\u76ee\\u304b\\u3089\\u306a\\u308b\\u6388\\u696d\\u3068\\u3001\\u5b9f\\u8df5\\u306e\\u5834\\u3092\\u63d0\\u4f9b\\u3059\\u308b\\u30c8\\u30e9\\u30a4\\u30a2\\u30eb\\u3067\\u69cb\\u6210\\u3055\\u308c\\u3066\\u3044\\u307e\\u3059\\u3002\\u3053\\u3053\\u306b\\u3042\\u308b\\u6a5f\\u4f1a\\u3092\\u98df\\u3089\\u3044\\u5c3d\\u304f\\u3057\\u3066\\u3001\\u672a\\u6765\\u3092\\u5207\\u308a\\u62d3\\u304f\\u7ce7\\u306b\\u3057\\u3066\\u304f\\u3060\\u3055\\u3044\\u3002\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/qrec.kyushu-u.ac.jp\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"[Change of lecture schedule] Advanced Lecture in Technology Based Entrepreneurship [For graduate students] - QREC \u4e5d\u5dde\u5927\u5b66\u30ed\u30d0\u30fc\u30c8\uff65\u30d5\u30a1\u30f3 \/\u30a2\u30f3\u30c8\u30ec\u30d7\u30ec\u30ca\u30fc\u30b7\u30c3\u30d7\uff65\u30bb\u30f3\u30bf\u30fc","description":"Fall quarter Fridays Lecture 6&7 Advanced Lecture in Technology Based Entrepreneurship There has been a change in the lecture schedule of the current Advanced Lecture in Technology Based Entrepreneurship course. \u3010Before the change\u3011 10\/8, 15, 22, 29, 11\/12, 19, 26, 12\/3 \u3010After the change\u3011 10\/8, 15, 22, 29,11\/5, 12, 19, 26,12\/3 *Please note that 11\/26","canonical_url":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/20211019e_2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/20211019e_2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/#listItem","position":1,"name":"TOP","item":"https:\/\/qrec.kyushu-u.ac.jp\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/#listItem","name":"\u8b1b\u7fa9\u30fb\u30a4\u30d9\u30f3\u30c8\u60c5\u5831"}},{"@type":"ListItem","@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/#listItem","position":2,"name":"\u8b1b\u7fa9\u30fb\u30a4\u30d9\u30f3\u30c8\u60c5\u5831","item":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/20211019e_2\/#listItem","name":"[Change of lecture schedule] Advanced Lecture in Technology Based Entrepreneurship [For graduate students]"},"previousItem":{"@type":"ListItem","@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/#listItem","name":"TOP"}},{"@type":"ListItem","@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/20211019e_2\/#listItem","position":3,"name":"[Change of lecture schedule] Advanced Lecture in Technology Based Entrepreneurship [For graduate students]","previousItem":{"@type":"ListItem","@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/#listItem","name":"\u8b1b\u7fa9\u30fb\u30a4\u30d9\u30f3\u30c8\u60c5\u5831"}}]},{"@type":"Organization","@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/#organization","name":"QREC","description":"QREC\u306f\u30a2\u30f3\u30c8\u30ec\u30d7\u30ec\u30ca\u30fc\u30b7\u30c3\u30d7\u306b\u3064\u3044\u3066\u5b66\u751f\u81ea\u3089\u304c\u5b66\u3076\u6a5f\u4f1a\u3092\u63d0\u4f9b\u3057\u3066\u3044\u307e\u3059\u300230\u4ee5\u4e0a\u306e\u79d1\u76ee\u304b\u3089\u306a\u308b\u6388\u696d\u3068\u3001\u5b9f\u8df5\u306e\u5834\u3092\u63d0\u4f9b\u3059\u308b\u30c8\u30e9\u30a4\u30a2\u30eb\u3067\u69cb\u6210\u3055\u308c\u3066\u3044\u307e\u3059\u3002\u3053\u3053\u306b\u3042\u308b\u6a5f\u4f1a\u3092\u98df\u3089\u3044\u5c3d\u304f\u3057\u3066\u3001\u672a\u6765\u3092\u5207\u308a\u62d3\u304f\u7ce7\u306b\u3057\u3066\u304f\u3060\u3055\u3044\u3002","url":"https:\/\/qrec.kyushu-u.ac.jp\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/qrec.kyushu-u.ac.jp\/kanri-new\/wp-content\/uploads\/2023\/09\/favicon-base.png","@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/20211019e_2\/#organizationLogo","width":260,"height":260},"image":{"@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/20211019e_2\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/20211019e_2\/#webpage","url":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/20211019e_2\/","name":"[Change of lecture schedule] Advanced Lecture in Technology Based Entrepreneurship [For graduate students] - QREC \u4e5d\u5dde\u5927\u5b66\u30ed\u30d0\u30fc\u30c8\uff65\u30d5\u30a1\u30f3 \/\u30a2\u30f3\u30c8\u30ec\u30d7\u30ec\u30ca\u30fc\u30b7\u30c3\u30d7\uff65\u30bb\u30f3\u30bf\u30fc","description":"Fall quarter Fridays Lecture 6&7 Advanced Lecture in Technology Based Entrepreneurship There has been a change in the lecture schedule of the current Advanced Lecture in Technology Based Entrepreneurship course. \u3010Before the change\u3011 10\/8, 15, 22, 29, 11\/12, 19, 26, 12\/3 \u3010After the change\u3011 10\/8, 15, 22, 29,11\/5, 12, 19, 26,12\/3 *Please note that 11\/26","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/#website"},"breadcrumb":{"@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/20211019e_2\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/qrec.kyushu-u.ac.jp\/kanri-new\/wp-content\/uploads\/2021\/10\/806b7c2575c5a21af601c3026ca0d2a0.png","@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/20211019e_2\/#mainImage","width":1920,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/20211019e_2\/#mainImage"},"datePublished":"2021-10-20T11:13:57+09:00","dateModified":"2021-10-20T11:13:57+09:00"},{"@type":"WebSite","@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/#website","url":"https:\/\/qrec.kyushu-u.ac.jp\/en\/","name":"QREC \u4e5d\u5dde\u5927\u5b66\u30ed\u30d0\u30fc\u30c8\uff65\u30d5\u30a1\u30f3 \/\u30a2\u30f3\u30c8\u30ec\u30d7\u30ec\u30ca\u30fc\u30b7\u30c3\u30d7\uff65\u30bb\u30f3\u30bf\u30fc","description":"QREC\u306f\u30a2\u30f3\u30c8\u30ec\u30d7\u30ec\u30ca\u30fc\u30b7\u30c3\u30d7\u306b\u3064\u3044\u3066\u5b66\u751f\u81ea\u3089\u304c\u5b66\u3076\u6a5f\u4f1a\u3092\u63d0\u4f9b\u3057\u3066\u3044\u307e\u3059\u300230\u4ee5\u4e0a\u306e\u79d1\u76ee\u304b\u3089\u306a\u308b\u6388\u696d\u3068\u3001\u5b9f\u8df5\u306e\u5834\u3092\u63d0\u4f9b\u3059\u308b\u30c8\u30e9\u30a4\u30a2\u30eb\u3067\u69cb\u6210\u3055\u308c\u3066\u3044\u307e\u3059\u3002\u3053\u3053\u306b\u3042\u308b\u6a5f\u4f1a\u3092\u98df\u3089\u3044\u5c3d\u304f\u3057\u3066\u3001\u672a\u6765\u3092\u5207\u308a\u62d3\u304f\u7ce7\u306b\u3057\u3066\u304f\u3060\u3055\u3044\u3002","inLanguage":"en-US","publisher":{"@id":"https:\/\/qrec.kyushu-u.ac.jp\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"QREC \u4e5d\u5dde\u5927\u5b66\u30ed\u30d0\u30fc\u30c8\uff65\u30d5\u30a1\u30f3 \/\u30a2\u30f3\u30c8\u30ec\u30d7\u30ec\u30ca\u30fc\u30b7\u30c3\u30d7\uff65\u30bb\u30f3\u30bf\u30fc","og:type":"article","og:title":"[Change of lecture schedule] Advanced Lecture in Technology Based Entrepreneurship [For graduate students] - QREC \u4e5d\u5dde\u5927\u5b66\u30ed\u30d0\u30fc\u30c8\uff65\u30d5\u30a1\u30f3 \/\u30a2\u30f3\u30c8\u30ec\u30d7\u30ec\u30ca\u30fc\u30b7\u30c3\u30d7\uff65\u30bb\u30f3\u30bf\u30fc","og:description":"Fall quarter Fridays Lecture 6&amp;7 Advanced Lecture in Technology Based Entrepreneurship There has been a change in the lecture schedule of the current Advanced Lecture in Technology Based Entrepreneurship course. \u3010Before the change\u3011 10\/8, 15, 22, 29, 11\/12, 19, 26, 12\/3 \u3010After the change\u3011 10\/8, 15, 22, 29,11\/5, 12, 19, 26,12\/3 *Please note that 11\/26","og:url":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/20211019e_2\/","og:image":"https:\/\/qrec.kyushu-u.ac.jp\/kanri-new\/wp-content\/uploads\/2023\/09\/ogp.png","og:image:secure_url":"https:\/\/qrec.kyushu-u.ac.jp\/kanri-new\/wp-content\/uploads\/2023\/09\/ogp.png","og:image:width":1200,"og:image:height":630,"article:published_time":"2021-10-20T02:13:57+00:00","article:modified_time":"2021-10-20T02:13:57+00:00","twitter:card":"summary_large_image","twitter:title":"[Change of lecture schedule] Advanced Lecture in Technology Based Entrepreneurship [For graduate students] - QREC \u4e5d\u5dde\u5927\u5b66\u30ed\u30d0\u30fc\u30c8\uff65\u30d5\u30a1\u30f3 \/\u30a2\u30f3\u30c8\u30ec\u30d7\u30ec\u30ca\u30fc\u30b7\u30c3\u30d7\uff65\u30bb\u30f3\u30bf\u30fc","twitter:description":"Fall quarter Fridays Lecture 6&amp;7 Advanced Lecture in Technology Based Entrepreneurship There has been a change in the lecture schedule of the current Advanced Lecture in Technology Based Entrepreneurship course. \u3010Before the change\u3011 10\/8, 15, 22, 29, 11\/12, 19, 26, 12\/3 \u3010After the change\u3011 10\/8, 15, 22, 29,11\/5, 12, 19, 26,12\/3 *Please note that 11\/26","twitter:image":"https:\/\/qrec.kyushu-u.ac.jp\/kanri-new\/wp-content\/uploads\/2023\/09\/ogp.png"},"aioseo_meta_data":{"post_id":"26906","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-09-24 12:36:08","updated":"2023-09-24 12:36:08","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/qrec.kyushu-u.ac.jp\/en\/\" title=\"TOP\">TOP<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u203a<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/\" title=\"\u8b1b\u7fa9\u30fb\u30a4\u30d9\u30f3\u30c8\u60c5\u5831\">\u8b1b\u7fa9\u30fb\u30a4\u30d9\u30f3\u30c8\u60c5\u5831<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u203a<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t[Change of lecture schedule] Advanced Lecture in Technology Based Entrepreneurship [For graduate students]\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"TOP","link":"https:\/\/qrec.kyushu-u.ac.jp\/en\/"},{"label":"\u8b1b\u7fa9\u30fb\u30a4\u30d9\u30f3\u30c8\u60c5\u5831","link":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/"},{"label":"[Change of lecture schedule] Advanced Lecture in Technology Based Entrepreneurship [For graduate students]","link":"https:\/\/qrec.kyushu-u.ac.jp\/en\/news\/20211019e_2\/"}],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/qrec.kyushu-u.ac.jp\/en\/wp-json\/wp\/v2\/news\/26906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qrec.kyushu-u.ac.jp\/en\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/qrec.kyushu-u.ac.jp\/en\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":0,"href":"https:\/\/qrec.kyushu-u.ac.jp\/en\/wp-json\/wp\/v2\/news\/26906\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qrec.kyushu-u.ac.jp\/en\/wp-json\/wp\/v2\/media\/26908"}],"wp:attachment":[{"href":"https:\/\/qrec.kyushu-u.ac.jp\/en\/wp-json\/wp\/v2\/media?parent=26906"}],"wp:term":[{"taxonomy":"newstag","embeddable":true,"href":"https:\/\/qrec.kyushu-u.ac.jp\/en\/wp-json\/wp\/v2\/newstag?post=26906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}